{"id":1618,"date":"2015-05-07T13:45:59","date_gmt":"2015-05-07T11:45:59","guid":{"rendered":"http:\/\/www.zerberos.com\/?p=478"},"modified":"2015-05-07T13:45:59","modified_gmt":"2015-05-07T11:45:59","slug":"e-banking-trojaner-dyre-rasche-verbreitung","status":"publish","type":"post","link":"https:\/\/www.netsolution.ch\/en\/2015\/05\/e-banking-trojaner-dyre-rasche-verbreitung\/","title":{"rendered":"E-Banking Trojaner \u201eDyre\u201c: Rasche Verbreitung"},"content":{"rendered":"<p>Im Februar 2015 hat die Melde- und Analysestelle Informationssicherung MELANI vor dem E-Banking Trojaner &#8220;Dyre&#8221; gewarnt, welcher Schweizer KMUs im Visier hat. In den vergangenen Wochen wurden MELANI t\u00e4glich mehrere hundert Neuinfektionen in der Schweiz gemeldet. Mittlerweile sind nicht mehr nur KMUs betroffen, sondern vermehrt auch Privatanwender.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-483 size-full\" src=\"http:\/\/www.zerberos.com\/wp-content\/uploads\/2015\/05\/dyre1.jpg\" alt=\"dyre1\" width=\"484\" height=\"548\" \/>Ist ein Computer mit dieser Schadsoftware infiziert, werden auf dem Computer\u00a0alle E-Mail-Adressen ausgelesen und dann unter dessen Absender\u00a0die Schadsoftware an alle Kontakte versendet. Dazu verwendet die Malware die\u00a0<em>msmapi32.dll<\/em>\u00a0Bibliothek (wird von Microsoft Outlook installiert und verwendet) \u00a0um die Mailfunktionen auszuf\u00fchren: Login, Mails versenden, Attachment anh\u00e4ngen.<\/p>\n<p>Das verseuchte E-Mail erreicht somit den ganzen\u00a0Kundenstamm einer Firma oder den\u00a0Bekanntenkreis einer Privatperson. Da der Absender des E-Mails dem Empf\u00e4nger bekannt und vertraut ist, ist die Risiko hoch, dass Empf\u00e4nger den Anhang \u00f6ffnen und so den Sch\u00e4dling installieren und weiterverbreiten.<\/p>\n<p>Die aktuelle Dyre Variante \u00fcberwacht dann den Datenverkehr zu 355 Finanzwebseiten &#8211; sobald eine dieser Seiten vom infizierten System aus aufgerufen wird werden die Zugangsdaten und andere Informationen gestohlen und an die Urheber des Angriffes \u00fcbermittelt. Betroffene Banken befinden sich haupts\u00e4chlich in den USA, z.B.\u00a0JP Morgan, Barclays, Bank of Melbourne, Citibank etc.<\/p>\n<p>Aufgrund der akuten Bedrohung durch Dyre gilt die MELANI Warnung vom Februar 2015 unver\u00e4ndert:<\/p>\n<p>User sollten\u00a0verd\u00e4chtigen E-Mail Anh\u00e4nge zu \u00f6ffnen. Die Schadsoftware tarnt sich unter anderem als Faxnachricht, erfundene Bestellung, Lieferung, Rechnung oder Zahlung.<\/p>\n<p>Die Betr\u00fcger denken sich immer wieder neue Szenarien aus, um die Empf\u00e4nger zu verleiten, auf den Anhang zu klicken oder einem Link zu folgen &#8211; hier ist also immer Vorsicht geboten. Mittels Security Awareness Trainings sollte dies auch allen Firmenmitarbeitern vermittelt werden.<\/p>\n<p>Anzahl der an MELANI gemeldete Neuinfektionen:<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-481 size-full\" src=\"http:\/\/www.zerberos.com\/wp-content\/uploads\/2015\/05\/dyyre-infections-ch.png\" alt=\"dyyre-infections-ch\" width=\"515\" height=\"382\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Februar 2015 hat die Melde- und Analysestelle Informationssicherung MELANI vor dem E-Banking Trojaner &#8220;Dyre&#8221; gewarnt, welcher Schweizer KMUs im Visier hat. In den vergangenen Wochen wurden MELANI t\u00e4glich mehrere hundert Neuinfektionen in der Schweiz gemeldet. Mittlerweile sind nicht mehr nur KMUs betroffen, sondern vermehrt auch Privatanwender. Ist ein Computer mit dieser Schadsoftware infiziert, werden &#8230; <a title=\"E-Banking Trojaner \u201eDyre\u201c: Rasche Verbreitung\" class=\"read-more\" href=\"https:\/\/www.netsolution.ch\/en\/2015\/05\/e-banking-trojaner-dyre-rasche-verbreitung\/\" aria-label=\"Read more about E-Banking Trojaner \u201eDyre\u201c: Rasche Verbreitung\">Read more<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","rank_math_focus_keyword":"","rank_math_title":"","rank_math_description":"","rank_math_robots":null,"rank_math_canonical_url":"","rank_math_primary_category":"","footnotes":""},"categories":[35],"tags":[86,87,88,39,78,79,49],"class_list":["post-1618","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-angriff","tag-dyre","tag-e-banking","tag-hacker-en","tag-malware","tag-online-banking","tag-virus-en"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"netsolution","author_link":"https:\/\/www.netsolution.ch\/en\/author\/netsolution\/"},"uagb_comment_info":0,"uagb_excerpt":"Im Februar 2015 hat die Melde- und Analysestelle Informationssicherung MELANI vor dem E-Banking Trojaner &#8220;Dyre&#8221; gewarnt, welcher Schweizer KMUs im Visier hat. In den vergangenen Wochen wurden MELANI t\u00e4glich mehrere hundert Neuinfektionen in der Schweiz gemeldet. Mittlerweile sind nicht mehr nur KMUs betroffen, sondern vermehrt auch Privatanwender. Ist ein Computer mit dieser Schadsoftware infiziert, werden&hellip;","_links":{"self":[{"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/posts\/1618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/comments?post=1618"}],"version-history":[{"count":0,"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/posts\/1618\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/media?parent=1618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/categories?post=1618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/tags?post=1618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}