{"id":1612,"date":"2015-03-05T11:12:16","date_gmt":"2015-03-05T09:12:16","guid":{"rendered":"http:\/\/www.zerberos.com\/?p=366"},"modified":"2015-03-05T11:12:16","modified_gmt":"2015-03-05T09:12:16","slug":"freak-attack","status":"publish","type":"post","link":"https:\/\/www.netsolution.ch\/en\/2015\/03\/freak-attack\/","title":{"rendered":"Freak Attack"},"content":{"rendered":"<p>Beim Freak Angriff wird dem Client bei einer SSL Verbindung eine schwache Verschl\u00fcsselung aufgezwungen welche sich einfach knacken l\u00e4sst.<\/p>\n<p>Zudem k\u00f6nnen bei entsprechend konfigurierten Servern die privaten Schl\u00fcssel abgegriffen werden &#8211; so kann sich ein Angreifer als eben diese Seite ausgeben.<\/p>\n<p>Ein Server ist verwundbar wenn er die RSA_EXPORT Cypher Suiten anbietet oder wenn er eine Version von OpenSSL verwendet welche die\u00a0<a href=\"https:\/\/cve.mitre.org\/cgi-bin\/cvename.cgi?name=CVE-2015-0204\" target=\"_blank\" rel=\"noopener\">CVE-2014-0204<\/a> Schwachstelle aufweist.<\/p>\n<p>Als Clients sind vor allem der Safari Browser auf Apple und der Android-Standardbrowser betroffen.<\/p>\n<p>Von den 1Mio meistaufgerufenen Webseiten sind 10% von der L\u00fccke betroffen &#8211; so z.B. auch die Webseiten www.americanexpress.com, groupon.com, nationalgeographic.com, whitehouse.com, zdnet.com, nsa.gov und viele weitere. Weltweit sind 30% aller Webseiten betroffen.<\/p>\n<p>Ihren Browser k\u00f6nnen Sie <a href=\"https:\/\/freakattack.com\/clienttest.html\" target=\"_blank\" rel=\"noopener\">hier auf Verwundbarkeit testen<\/a>.<\/p>\n<p>Weitere Details finden Sie bei <a href=\"https:\/\/freakattack.com\" target=\"_blank\" rel=\"noopener\">Freakattak.com<\/a> ,<a href=\"http:\/\/blog.cryptographyengineering.com\/2015\/03\/attack-of-week-freak-or-factoring-nsa.html\" target=\"_blank\" rel=\"noopener\">Matt Green<\/a>, <a href=\"http:\/\/www.washingtonpost.com\/blogs\/the-switch\/wp\/2015\/03\/03\/freak-flaw-undermines-security-for-apple-and-google-users-researchers-discover\/\" target=\"_blank\" rel=\"noopener\">The Washington Post<\/a>, <a href=\"http:\/\/www.heise.de\/security\/meldung\/Freak-Attack-SSL-Verschluesselung-von-Millionen-Webseiten-angreifbar-2566444.html?wt_mc=sm.feed.tw.security\" target=\"_blank\" rel=\"noopener\">heise.de<\/a><\/p>\n<p>Bei Fragen zu Freak Attack k\u00f6nnen Sie uns <a href=\"http:\/\/www.zerberos.com\/kontakt\/\" target=\"_blank\" rel=\"noopener\">hier kontaktieren<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Beim Freak Angriff wird dem Client bei einer SSL Verbindung eine schwache Verschl\u00fcsselung aufgezwungen welche sich einfach knacken l\u00e4sst. Zudem k\u00f6nnen bei entsprechend konfigurierten Servern die privaten Schl\u00fcssel abgegriffen werden &#8211; so kann sich ein Angreifer als eben diese Seite ausgeben. Ein Server ist verwundbar wenn er die RSA_EXPORT Cypher Suiten anbietet oder wenn er &#8230; <a title=\"Freak Attack\" class=\"read-more\" href=\"https:\/\/www.netsolution.ch\/en\/2015\/03\/freak-attack\/\" aria-label=\"Read more about Freak Attack\">Read more<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","rank_math_focus_keyword":"","rank_math_title":"","rank_math_description":"","rank_math_robots":null,"rank_math_canonical_url":"","rank_math_primary_category":"","footnotes":""},"categories":[35],"tags":[60,73,55],"class_list":["post-1612","post","type-post","status-publish","format-standard","hentry","category-allgemein","tag-exploit","tag-freack-attack","tag-vulnerability"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"netsolution","author_link":"https:\/\/www.netsolution.ch\/en\/author\/netsolution\/"},"uagb_comment_info":0,"uagb_excerpt":"Beim Freak Angriff wird dem Client bei einer SSL Verbindung eine schwache Verschl\u00fcsselung aufgezwungen welche sich einfach knacken l\u00e4sst. Zudem k\u00f6nnen bei entsprechend konfigurierten Servern die privaten Schl\u00fcssel abgegriffen werden &#8211; so kann sich ein Angreifer als eben diese Seite ausgeben. Ein Server ist verwundbar wenn er die RSA_EXPORT Cypher Suiten anbietet oder wenn er&hellip;","_links":{"self":[{"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/posts\/1612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/comments?post=1612"}],"version-history":[{"count":0,"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/posts\/1612\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/media?parent=1612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/categories?post=1612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/tags?post=1612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}