{"id":1594,"date":"2013-10-19T19:32:41","date_gmt":"2013-10-19T17:32:41","guid":{"rendered":"http:\/\/www.zerberos.com\/?p=256"},"modified":"2013-10-19T19:32:41","modified_gmt":"2013-10-19T17:32:41","slug":"ethical-hacking","status":"publish","type":"post","link":"https:\/\/www.netsolution.ch\/en\/2013\/10\/ethical-hacking\/","title":{"rendered":"Ethical Hacking"},"content":{"rendered":"<p>Was ist Ethical Hacking?<\/p>\n<p>Ein Ethical Hacker greift ein System im Auftrag der Besitzer dieses Systems an um die Sicherheit des Systems zu pr\u00fcfen.<\/p>\n<p>Mit den Resultaten eines sogenannten Penetration Tests oder Pentest kann der Auftraggeber anschliessend die Sicherheit seiner Webserver und Webapplikation verbessern.<\/p>\n<p>Zerberos mit Sitz in Z\u00fcrich in der Schweiz bietet solche Penetrationstests an &#8211; so k\u00f6nnen Sicherheitsl\u00fccken auf Webservern gefunden und behoben werden bevor b\u00f6swillige Hacker diese ausn\u00fctzen.<\/p>\n<p>Falls bereits ein Hacker in ein System eingedrungen ist kann Zerberos dessen Spuren erfassen und nachvollziehen was auf dem System gemacht wurde &#8211; anschliessend kann das System neu aufgesetzt werden und die gefundenen Indizien ebenfalls f\u00fcr eine Verbesserung der Sicherheit verwendet werden.<\/p>\n<p>Der Website Sicherheitstest empfiehlt sich auch immer dann wenn an der Webapplikation \u00c4nderungen gemacht wurden oder die Server Infrastruktur ge\u00e4ndert wurde &#8211; in diesem Kontext k\u00f6nnen neue L\u00fccken auftauchen die von bisherigen Sicherheitspr\u00fcfungen noch nicht erfasst wurden.<\/p>\n<p><a href=\"http:\/\/www.zerberos.com\/kontakt\/\" target=\"_blank\" rel=\"noopener\">Kontaktieren<\/a> Sie uns heute noch f\u00fcr eine unverbindliche Beratung!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was ist Ethical Hacking? Ein Ethical Hacker greift ein System im Auftrag der Besitzer dieses Systems an um die Sicherheit des Systems zu pr\u00fcfen. Mit den Resultaten eines sogenannten Penetration Tests oder Pentest kann der Auftraggeber anschliessend die Sicherheit seiner Webserver und Webapplikation verbessern. Zerberos mit Sitz in Z\u00fcrich in der Schweiz bietet solche Penetrationstests &#8230; <a title=\"Ethical Hacking\" class=\"read-more\" href=\"https:\/\/www.netsolution.ch\/en\/2013\/10\/ethical-hacking\/\" aria-label=\"Read more about Ethical Hacking\">Read more<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","rank_math_focus_keyword":"","rank_math_title":"Ethical Hacking - Zerberos Z\u00fcrich","rank_math_description":"","rank_math_robots":null,"rank_math_canonical_url":"","rank_math_primary_category":"","footnotes":""},"categories":[35],"tags":[],"class_list":["post-1594","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"netsolution","author_link":"https:\/\/www.netsolution.ch\/en\/author\/netsolution\/"},"uagb_comment_info":0,"uagb_excerpt":"Was ist Ethical Hacking? Ein Ethical Hacker greift ein System im Auftrag der Besitzer dieses Systems an um die Sicherheit des Systems zu pr\u00fcfen. Mit den Resultaten eines sogenannten Penetration Tests oder Pentest kann der Auftraggeber anschliessend die Sicherheit seiner Webserver und Webapplikation verbessern. Zerberos mit Sitz in Z\u00fcrich in der Schweiz bietet solche Penetrationstests&hellip;","_links":{"self":[{"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/posts\/1594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/comments?post=1594"}],"version-history":[{"count":0,"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/posts\/1594\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/media?parent=1594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/categories?post=1594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/tags?post=1594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}