{"id":1592,"date":"2013-11-15T19:21:57","date_gmt":"2013-11-15T17:21:57","guid":{"rendered":"http:\/\/www.zerberos.com\/?p=252"},"modified":"2013-11-15T19:21:57","modified_gmt":"2013-11-15T17:21:57","slug":"anonymous-hat-monatelang-zugriff-auf-us-regierungsserver","status":"publish","type":"post","link":"https:\/\/www.netsolution.ch\/en\/2013\/11\/anonymous-hat-monatelang-zugriff-auf-us-regierungsserver\/","title":{"rendered":"Anonymous hat monatelang Zugriff auf US Regierungsserver"},"content":{"rendered":"<p>Die Nachrichtenagentur Reuters <a href=\"http:\/\/www.reuters.com\/article\/2013\/11\/15\/us-usa-security-anonymous-fbi-idUSBRE9AE17C20131115\" target=\"_blank\" rel=\"noopener\">berichtet<\/a> dass die Hackergruppe Anonymous jahrelang Zugang auf US Regierungsserver hatte.<\/p>\n<p>Der betroffene Server wurde \u00fcber eine Sicherheitsl\u00fccke in Cold Fusion angegriffen.<\/p>\n<p>Auf dem Server lagen pers\u00f6nliche Informationen von mehr als 100&#8217;000 Mitarbeitern sowie Angeh\u00f6rigen.<\/p>\n<p>Eine Beschreibung der Sicherheitsl\u00fccke befindet sich <a href=\"https:\/\/www.it.cornell.edu\/services\/alert.cfm?id=2419\" target=\"_blank\" rel=\"noopener\">hier<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Nachrichtenagentur Reuters berichtet dass die Hackergruppe Anonymous jahrelang Zugang auf US Regierungsserver hatte. Der betroffene Server wurde \u00fcber eine Sicherheitsl\u00fccke in Cold Fusion angegriffen. Auf dem Server lagen pers\u00f6nliche Informationen von mehr als 100&#8217;000 Mitarbeitern sowie Angeh\u00f6rigen. Eine Beschreibung der Sicherheitsl\u00fccke befindet sich hier.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","rank_math_focus_keyword":"","rank_math_title":"","rank_math_description":"","rank_math_robots":null,"rank_math_canonical_url":"","rank_math_primary_category":"","footnotes":""},"categories":[35],"tags":[],"class_list":["post-1592","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"netsolution","author_link":"https:\/\/www.netsolution.ch\/en\/author\/netsolution\/"},"uagb_comment_info":0,"uagb_excerpt":"Die Nachrichtenagentur Reuters berichtet dass die Hackergruppe Anonymous jahrelang Zugang auf US Regierungsserver hatte. Der betroffene Server wurde \u00fcber eine Sicherheitsl\u00fccke in Cold Fusion angegriffen. Auf dem Server lagen pers\u00f6nliche Informationen von mehr als 100&#8217;000 Mitarbeitern sowie Angeh\u00f6rigen. Eine Beschreibung der Sicherheitsl\u00fccke befindet sich hier.","_links":{"self":[{"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/posts\/1592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/comments?post=1592"}],"version-history":[{"count":0,"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/posts\/1592\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/media?parent=1592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/categories?post=1592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.netsolution.ch\/en\/wp-json\/wp\/v2\/tags?post=1592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}